{"id":4411,"date":"2020-05-16T16:54:25","date_gmt":"2020-05-16T13:54:25","guid":{"rendered":"https:\/\/hqstore.ro\/index.php\/product\/procesoare-server-hpe-ml350-gen10-intel-xeon-gold-6242-2-8ghz-16-core-150w-processor-kit-p10949-b21\/"},"modified":"2023-05-26T23:10:27","modified_gmt":"2023-05-26T20:10:27","slug":"procesoare-server-hpe-ml350-gen10-6242-kit-p10949-b21","status":"publish","type":"product","link":"https:\/\/hqstore.ro\/index.php\/product\/procesoare-server-hpe-ml350-gen10-6242-kit-p10949-b21\/","title":{"rendered":"HPE ML350 Gen10 6242 Kit"},"content":{"rendered":"<h4>Lifecycle<\/h4>\n<ul>\n<li><b>Obsolete Date<\/b> 28-02-2021<\/a><\/li>\n<li><b>End of support date<\/b> 28-02-2026<\/a><\/li>\n<\/ul>\n<h4>Specifications<\/h4>\n<ul>\n<li><b>Weight<\/b> 4.409 lb<\/li>\n<li><b>Weight<\/b> 2 kg<\/li>\n<li><b>Product dimensions (H x W x D)<\/b> 7.87 x 11.81 x 7.87 in<\/li>\n<li><b>Minimum dimensions ( H x W x D)<\/b> 19.99 x 30 x 19.99 cm<\/li>\n<li><b>Power Consumption<\/b> 150W<\/li>\n<li><b>Processor speed<\/b> 2.8 GHz<\/li>\n<li><b>Server Platform<\/b> HPE ProLiant ML350<\/li>\n<li><b>Cores<\/b> 16 cores<\/li>\n<li><b>Generation<\/b> Gen10<\/li>\n<\/ul>\n<h4>Compatible products<\/h4>\n<ul class=\"more-details compatible-products\">\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=877619-421\">HPE ML350 GEN10 3104 1P 4LFF NHP SVR\/TV<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=877620-421\">HPE ML350 Gen10 3106 1P 16G 4LFF Svr\/TV<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=877621-421\">HPE ML350 Gen10 4110 1P 16G 8SFF Svr<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=877622-421\">HPE ML350 Gen10 4114 2P 32G 8SFF Rck Svr<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=877623-421\">HPE ML350 Gen10 5118 2P 32G 8SFF Svr<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=P04674-425\">HPE ProLiant ML350 Gen10 4110 1P 16GB-R E208i-a 8SFF 1x800W RPS Solution Svr<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=P11048-421\">HPE ProLiant ML350 Gen10 3204 1P 8GB-R S100i 4LFF-NHP 500W PS Server<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=P11049-421\">HPE ProLiant ML350 Gen10 3204 1P 16GB-R S100i 4LFF 1x500W RPS Server<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=P11050-421\">HPE ProLiant ML350 Gen10 4208 1P 16GB-R E208i-a 4LFF 1x500W RPS Server<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=P11051-421\">HPE ProLiant ML350 Gen10 4210 1P 16GB-R P408i-a 8SFF 1x800W RPS Server<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=P11052-421\">HPE ProLiant ML350 Gen10 4214 1P 32GB-R P408i-a 8SFF 1x800W RPS Server<\/a><\/li>\n<li class=\"cross-sell\"><a href=\"https:\/\/b2b.nod.ro\/products\/product\/?code=P11053-421\">HPE ProLiant ML350 Gen10 5218 1P 32GB-R P408i-a 8SFF 2x800W RPS Server<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Lifecycle Obsolete Date 28-02-2021 End of support date 28-02-2026 Specifications Weight 4.409 lb Weight 2 kg Product dimensions (H x W x D) 7.87 x 11.81 x 7.87 in Minimum dimensions ( H x W x D) 19.99 x 30 x 19.99 cm Power Consumption 150W Processor speed 2.8 GHz Server Platform HPE ProLiant ML350<span class=\"read-more-faq\"><a href=\"https:\/\/hqstore.ro\/index.php\/product\/procesoare-server-hpe-ml350-gen10-6242-kit-p10949-b21\/\">Read More<\/a><\/span><\/p>\n","protected":false},"featured_media":4412,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[349],"product_tag":[],"_links":{"self":[{"href":"https:\/\/hqstore.ro\/index.php\/wp-json\/wp\/v2\/product\/4411"}],"collection":[{"href":"https:\/\/hqstore.ro\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hqstore.ro\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hqstore.ro\/index.php\/wp-json\/wp\/v2\/comments?post=4411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hqstore.ro\/index.php\/wp-json\/wp\/v2\/media\/4412"}],"wp:attachment":[{"href":"https:\/\/hqstore.ro\/index.php\/wp-json\/wp\/v2\/media?parent=4411"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hqstore.ro\/index.php\/wp-json\/wp\/v2\/product_cat?post=4411"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hqstore.ro\/index.php\/wp-json\/wp\/v2\/product_tag?post=4411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}